{"id":9057,"date":"2017-09-27T14:25:28","date_gmt":"2017-09-27T18:25:28","guid":{"rendered":"http:\/\/cahuntsic.ca\/bulletin-express\/?p=9057"},"modified":"2017-10-02T16:37:57","modified_gmt":"2017-10-02T20:37:57","slug":"un-article-dyves-vaillancourt-dans-la-revue-possibles","status":"publish","type":"post","link":"https:\/\/cahuntsic.ca\/bulletin-express\/un-article-dyves-vaillancourt-dans-la-revue-possibles\/","title":{"rendered":"Un article d&rsquo;Yves Vaillancourt dans la revue Possibles"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"size-medium wp-image-9086 alignleft\" src=\"http:\/\/cahuntsic.ca\/bulletin-express\/wp-content\/uploads\/2017\/09\/Revue_possibles-233x300.jpg\" alt=\"\" width=\"233\" height=\"300\" \/>Yves Vaillancourt, enseignant en philosophie, publie un article intitul\u00e9 <i class=\"\">Exister: pour un Humanisme de l\u2019Anthropoc\u00e8ne\u00a0<\/i>dans le prochain num\u00e9ro de la revue multidisciplinaire <strong>Possibles<\/strong>. Lors du lancement qui aura lieu le jeudi 5 octobre, M. Vaillancourt prendra part \u00e0 une table ronde sur le th\u00e8me abord\u00e9 par ce num\u00e9ro de Possibles : la justice \u00e9cologique.<\/p>\n<p><strong>Date\u00a0<\/strong>: le jeudi 5 octobre 2017<\/p>\n<p><strong>Heure\u00a0<\/strong>: 16h30 \u00e0 20h<\/p>\n<p><strong>Lieu\u00a0<\/strong>: Carrefour des Arts et des Sciences, C-3061, Pavillon Lionel Groulx (3150 Jean-Brillant) Universit\u00e9 de Montr\u00e9al.<\/p>\n<p>&nbsp;<\/p>\n<p>Source: Direction des communications<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Yves Vaillancourt, enseignant en philosophie, publie un article intitul\u00e9 Exister: pour un Humanisme de l\u2019Anthropoc\u00e8ne\u00a0dans le prochain num\u00e9ro de la revue multidisciplinaire Possibles. Lors du lancement qui aura lieu le jeudi 5 octobre, M. Vaillancourt prendra part \u00e0 une table ronde sur le th\u00e8me abord\u00e9 par ce num\u00e9ro de Possibles : la justice \u00e9cologique. Date\u00a0: [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5867,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_expiration-date-status":"saved","_expiration-date":0,"_expiration-date-type":"","_expiration-date-categories":[],"_expiration-date-options":[]},"categories":[18],"tags":[],"_links":{"self":[{"href":"https:\/\/cahuntsic.ca\/bulletin-express\/wp-json\/wp\/v2\/posts\/9057"}],"collection":[{"href":"https:\/\/cahuntsic.ca\/bulletin-express\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cahuntsic.ca\/bulletin-express\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cahuntsic.ca\/bulletin-express\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cahuntsic.ca\/bulletin-express\/wp-json\/wp\/v2\/comments?post=9057"}],"version-history":[{"count":11,"href":"https:\/\/cahuntsic.ca\/bulletin-express\/wp-json\/wp\/v2\/posts\/9057\/revisions"}],"predecessor-version":[{"id":9148,"href":"https:\/\/cahuntsic.ca\/bulletin-express\/wp-json\/wp\/v2\/posts\/9057\/revisions\/9148"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cahuntsic.ca\/bulletin-express\/wp-json\/wp\/v2\/media\/5867"}],"wp:attachment":[{"href":"https:\/\/cahuntsic.ca\/bulletin-express\/wp-json\/wp\/v2\/media?parent=9057"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cahuntsic.ca\/bulletin-express\/wp-json\/wp\/v2\/categories?post=9057"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cahuntsic.ca\/bulletin-express\/wp-json\/wp\/v2\/tags?post=9057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}